{"id":2937,"date":"2018-09-19T14:57:01","date_gmt":"2018-09-19T12:57:01","guid":{"rendered":"https:\/\/www.sideaita.it\/?p=2937"},"modified":"2024-06-11T12:28:42","modified_gmt":"2024-06-11T10:28:42","slug":"motus-kopfuber-bewegung","status":"publish","type":"post","link":"https:\/\/www.sideaita.it\/de\/2018\/09\/19\/motus-upside-down-movement\/","title":{"rendered":"MOTUS: eine umgekehrte Sichtweise auf die Bewegung"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p align=\"justify\">\"<em>Die Natur des Menschen ist in Bewegung: v\u00f6llige Ruhe ist der Tod<\/em>\" (B. Pascal). Dass die\u00a0<strong>Bewegung<\/strong>\u00a0eine Schl\u00fcsselrolle f\u00fcr das Wesen des Menschen spielt, wurde bereits im 17. Jahrhundert deutlich:\u00a0<strong>durch sie kann Energie erzeugt werden<\/strong>aber auch feststellen, dass<strong>psychophysische Harmonie\u00a0<\/strong>die es dem Menschen erm\u00f6glicht, sein Potenzial voll zum Ausdruck zu bringen. In ihren verschiedenen Formen schafft die Bewegung die Voraussetzungen f\u00fcr eine\u00a0<strong>einen gesunden und aktiven Lebensstil,<\/strong>\u00a0Dies steht im Gegensatz zu der zunehmenden Sesshaftigkeit, die einen immer gr\u00f6\u00dferen Teil unseres t\u00e4glichen Lebens ausmacht. Wir sitzen, wenn wir arbeiten oder lernen, wir sitzen, wenn wir essen, wir sitzen, wenn wir uns von einem Ort zum anderen bewegen, und wir sitzen oft sogar, wenn wir Sport treiben.<\/p>\n\n  \n    <div id=\"gallery-1161071727\" class=\"lightbox-multi-gallery slider slider-auto-height row-collapse slider-nav-reveal\" data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 7000}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"579\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695.jpg\" class=\"attachment-original size-original\" alt=\"Motus Handstandwerkstatt e1536675924695\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-700x540.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-518x400.jpg 518w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-600x463.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-510x394.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-510x765.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-600x900.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"618\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819.jpg\" class=\"attachment-original size-original\" alt=\"Motus Handstandwerkstatt e1536675956819\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-700x577.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-485x400.jpg 485w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-600x494.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-510x420.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237.jpg\" class=\"attachment-original size-original\" alt=\"Motus Handstandwerkstatt e1536675894237\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-300x300.jpg 300w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-100x100.jpg 100w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-700x700.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-280x280.jpg 280w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-400x400.jpg 400w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-510x510.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-600x600.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-600x900.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-510x765.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-600x900.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-510x765.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-510x765.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-600x900.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-700x394.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-711x400.jpg 711w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-510x287.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-600x338.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-700x394.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-711x400.jpg 711w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-600x338.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-510x287.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-450x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"610\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-700x569.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-492x400.jpg 492w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-600x488.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-510x415.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n<p align=\"justify\">Eine Antwort auf diesen Trend gibt ein in Rom geborenes Projekt, das die\u00a0<strong>R\u00fcckkehr zur Bewegung<\/strong>\u00a0seinen Schwerpunkt und vereint verschiedene Stile, Ans\u00e4tze und F\u00e4higkeiten um dieses Ziel herum:\u00a0<strong>Motus<\/strong>\u00a0('Bewegung' auf Lateinisch) ist <a href=\"https:\/\/www.instagram.com\/lifemotus\/\">eine Praxis, die auf die Beherrschung des eigenen K\u00f6rpers als Ausdruck von Freiheit und psychophysischem Wohlbefinden abzielt<\/a>.<\/p>\n<p align=\"justify\">Das Team Motus, das sich aus Pers\u00f6nlichkeiten mit sehr unterschiedlichem Hintergrund zusammensetzt, vereint multidisziplin\u00e4re Ans\u00e4tze, die auf ein einziges Ziel ausgerichtet sind, n\u00e4mlich die bewusste Erforschung der menschlichen Dimension und ihres Potenzials durch Bewegung. Eine Art kleine Revolution im Lebensstil der Menschen, f\u00fcr die keine professionelle Ausbildung erforderlich ist, da es sich um einen schrittweisen und progressiven Ansatz handelt, sondern um die einfache Neugier, das Leben aktiv und dynamisch zu leben, daran teilzunehmen und es nicht zu ertragen.<\/p>\n\n  \n    <div id=\"gallery-1086128205\" class=\"lightbox-multi-gallery slider slider-auto-height row-collapse slider-nav-reveal\" data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 7000}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"459\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-700x428.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-654x400.jpg 654w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-600x367.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-510x312.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30.jpg\" class=\"attachment-original size-original\" alt=\"motus-handstand-werkstatt\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32.jpg\" class=\"attachment-original size-original\" alt=\"Motus-Handstand-Workshop\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n<p align=\"justify\"><strong>Kraft, Flexibilit\u00e4t, Gelenkbeweglichkeit, Koordination, Geschicklichkeit, Konzentration und Mut<\/strong>Dies sind nur einige der Aspekte, bei denen der Ansatz von\u00a0<strong>Motus<\/strong>der zu den Hauptdarstellern des j\u00fcngsten Films<strong> <a href=\"https:\/\/www.sideaita.it\/de\/2018\/09\/10\/sidea-open-weekend-2018\/\">Sidea Open Weekend<\/a>.\u00a0<\/strong><\/p>\n<p align=\"justify\">Die drei Ausbilder der\u00a0<strong>Team Motus,\u00a0<a href=\"https:\/\/www.instagram.com\/kaddarina.motus\/\">Katharina Loestzsch<\/a>,\u00a0<a href=\"https:\/\/www.instagram.com\/lelepagliuca\/\">Emanuele Pagliuca<\/a>\u00a0und\u00a0<a href=\"https:\/\/www.instagram.com\/riccardocollins\/\">Richard Collins<\/a>,<\/strong>\u00a0veranstaltete Workshops mit dem Titel \"<strong>Motus Handstand und \u00dcberg\u00e4nge: ein umgedrehter Blickwinkel<\/strong>\" zum freien Handstand und allgemeiner zu dynamischen Bewegungen am Boden, um unmittelbare Verbesserungen in der\u00a0<strong>Stabilit\u00e4t und Gleichgewichtssinn<\/strong>. \"Ein umgedrehter Standpunkt\", der also nicht nur bedeutet, sich physisch auf den Kopf zu stellen, sondern auch metaphorisch den Versuch dieser Gruppe zusammenfasst, ihre Einstellung zum Alltag umzukehren. Sich daran erinnern, dass \"<strong>das Wesen des Menschen liegt in der Bewegung<\/strong>\".<\/p>\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/xfSxu9ybqrs?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\n  <div class=\"banner has-hover\" id=\"banner-561771068\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"319\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2024\/02\/COPERTINA-MAILING-DISCHI-DA-PL-2--1400x438.jpg\" class=\"bg attachment-large size-large\" alt=\"ABDECKUNG DER POSTWURFSENDUNGEN VON PL 2\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1688827815\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1784889847\" class=\"text\">\n\t\t\n<p><strong>NEWSLETTER SEITEA<\/strong><\/p>\n<p>Abonnieren Sie unseren Newsletter, um Neuigkeiten, Sonderangebote und Einblicke in die Welt von Sidea zu erhalten.<br \/>\n\t\t\n<style>\n#text-1784889847 {\n  font-size: 1.45rem;\n  line-height: 1.25;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"http:\/\/eepurl.com\/iD9wQo\" class=\"button white is-outline is-large\" style=\"border-radius:26px;\">\n\t\t<span>JOIN<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1688827815 {\n  width: 60%;\n}\n#text-box-1688827815 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-561771068 {\n  padding-top: 300px;\n  background-color: rgb(0, 0, 0);\n}\n#banner-561771068 .overlay {\n  background-color: rgba(0, 0, 0, 0.669);\n}\n<\/style>\n  <\/div>","protected":false},"excerpt":{"rendered":"<p>Motus verbindet multidisziplin\u00e4re Ans\u00e4tze, die auf ein einziges Ziel ausgerichtet sind: die Erkundung der menschlichen Dimension und ihres Potenzials durch Bewegung.<\/p>","protected":false},"author":3,"featured_media":2940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11447],"tags":[294,278,276],"class_list":["post-2937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-calisthenics","tag-functional-training","tag-sidea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MOTUS: an upside-down point of view on Movement - Sidea Fitness<\/title>\n<meta name=\"description\" content=\"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sideaita.it\/de\/2018\/09\/19\/motus-kopfuber-bewegung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MOTUS: an upside-down point of view on Movement\" \/>\n<meta property=\"og:description\" content=\"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sideaita.it\/de\/2018\/09\/19\/motus-kopfuber-bewegung\/\" \/>\n<meta property=\"og:site_name\" content=\"Sidea | Attrezzatura Fitness Professionale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sideaita\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-19T12:57:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T10:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sidea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sidea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\"},\"author\":{\"name\":\"Sidea\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/person\\\/dffac77f9ef1c6ee0bee663f15d9de31\"},\"headline\":\"MOTUS: an upside-down point of view on Movement\",\"datePublished\":\"2018-09-19T12:57:01+00:00\",\"dateModified\":\"2024-06-11T10:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\"},\"wordCount\":500,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"keywords\":[\"calisthenics\",\"functional training\",\"sidea\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\",\"name\":\"MOTUS: an upside-down point of view on Movement - Sidea Fitness\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"datePublished\":\"2018-09-19T12:57:01+00:00\",\"dateModified\":\"2024-06-11T10:28:42+00:00\",\"description\":\"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"width\":1080,\"height\":607,\"caption\":\"motus-workshop-sidea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sideaita.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MOTUS: an upside-down point of view on Movement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/\",\"name\":\"Sidea | Attrezzatura Fitness Professionale\",\"description\":\"SIDEA \u2013 Allenati, diventa pi\u00f9 forte, vivi meglio | Attrezzatura professionale per la preparazione fisica ed il functional training. Nata dalla passione per lo sport, sviluppata per le palestre.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sideaita.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\",\"name\":\"Sidea Srl\",\"alternateName\":\"Sidea\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-solo-s-1440x1440-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-solo-s-1440x1440-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sidea Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sideaita\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sidea_fitness\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sideafitness\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/sideafitness\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FitnessIT\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sidea_fitness\"],\"description\":\"SIDEA \u2013 Allenati, diventa pi\u00f9 forte, vivi meglio | Attrezzatura professionale per la preparazione fisica ed il functional training. Nata dalla passione per lo sport, sviluppata per le palestre.\",\"email\":\"sidea@sideaita.it\",\"legalName\":\"Sidea Srl\",\"vatID\":\"IT02693190403\",\"taxID\":\"IT02693190403\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.sideaita.it\\\/de\\\/termini-condizioni-di-vendita\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/person\\\/dffac77f9ef1c6ee0bee663f15d9de31\",\"name\":\"Sidea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g\",\"caption\":\"Sidea\"},\"sameAs\":[\"riccardo\"],\"url\":\"https:\\\/\\\/www.sideaita.it\\\/de\\\/author\\\/gioele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MOTUS: eine auf den Kopf gestellte Sichtweise der Bewegung - Sidea Fitness","description":"Motus verbindet multidisziplin\u00e4re Ans\u00e4tze, die auf ein einziges Ziel ausgerichtet sind: die Erforschung der menschlichen Dimension und ihres Potenzials durch Bewegung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sideaita.it\/de\/2018\/09\/19\/motus-kopfuber-bewegung\/","og_locale":"de_DE","og_type":"article","og_title":"MOTUS: an upside-down point of view on Movement","og_description":"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento","og_url":"https:\/\/www.sideaita.it\/de\/2018\/09\/19\/motus-kopfuber-bewegung\/","og_site_name":"Sidea | Attrezzatura Fitness Professionale","article_publisher":"https:\/\/www.facebook.com\/sideaita\/","article_published_time":"2018-09-19T12:57:01+00:00","article_modified_time":"2024-06-11T10:28:42+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","type":"image\/jpeg"}],"author":"Sidea","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sidea","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#article","isPartOf":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/"},"author":{"name":"Sidea","@id":"https:\/\/www.sideaita.it\/#\/schema\/person\/dffac77f9ef1c6ee0bee663f15d9de31"},"headline":"MOTUS: an upside-down point of view on Movement","datePublished":"2018-09-19T12:57:01+00:00","dateModified":"2024-06-11T10:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/"},"wordCount":500,"commentCount":0,"publisher":{"@id":"https:\/\/www.sideaita.it\/#organization"},"image":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","keywords":["calisthenics","functional training","sidea"],"articleSection":["Eventi"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/","url":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/","name":"MOTUS: eine auf den Kopf gestellte Sichtweise der Bewegung - Sidea Fitness","isPartOf":{"@id":"https:\/\/www.sideaita.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage"},"image":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","datePublished":"2018-09-19T12:57:01+00:00","dateModified":"2024-06-11T10:28:42+00:00","description":"Motus verbindet multidisziplin\u00e4re Ans\u00e4tze, die auf ein einziges Ziel ausgerichtet sind: die Erforschung der menschlichen Dimension und ihres Potenzials durch Bewegung","breadcrumb":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage","url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","contentUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","width":1080,"height":607,"caption":"motus-workshop-sidea"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sideaita.it\/"},{"@type":"ListItem","position":2,"name":"MOTUS: an upside-down point of view on Movement"}]},{"@type":"WebSite","@id":"https:\/\/www.sideaita.it\/#website","url":"https:\/\/www.sideaita.it\/","name":"Sidea | Professionelle Fitnessger\u00e4te","description":"SIDEA - Trainieren, st\u00e4rker werden, besser leben | Professionelle Ausr\u00fcstung f\u00fcr k\u00f6rperliche Vorbereitung und funktionelles Training. Geboren aus einer Leidenschaft f\u00fcr den Sport, entwickelt f\u00fcr Fitnessstudios.","publisher":{"@id":"https:\/\/www.sideaita.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sideaita.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.sideaita.it\/#organization","name":"Sidea Srl","alternateName":"Sidea","url":"https:\/\/www.sideaita.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sideaita.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2023\/06\/cropped-logo-solo-s-1440x1440-1.jpg","contentUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2023\/06\/cropped-logo-solo-s-1440x1440-1.jpg","width":512,"height":512,"caption":"Sidea Srl"},"image":{"@id":"https:\/\/www.sideaita.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sideaita\/","https:\/\/www.instagram.com\/sidea_fitness\/","https:\/\/www.linkedin.com\/company\/sideafitness\/","https:\/\/www.pinterest.it\/sideafitness\/","https:\/\/www.youtube.com\/user\/FitnessIT\/","https:\/\/www.tiktok.com\/@sidea_fitness"],"description":"SIDEA - Trainieren, st\u00e4rker werden, besser leben | Professionelle Ausr\u00fcstung f\u00fcr k\u00f6rperliche Vorbereitung und funktionelles Training. Geboren aus einer Leidenschaft f\u00fcr den Sport, entwickelt f\u00fcr Fitnessstudios.","email":"sidea@sideaita.it","legalName":"Sidea Srl","vatID":"IT02693190403","taxID":"IT02693190403","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.sideaita.it\/de\/termini-condizioni-di-vendita\/"}},{"@type":"Person","@id":"https:\/\/www.sideaita.it\/#\/schema\/person\/dffac77f9ef1c6ee0bee663f15d9de31","name":"Sidea","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g","caption":"Sidea"},"sameAs":["riccardo"],"url":"https:\/\/www.sideaita.it\/de\/author\/gioele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/posts\/2937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/comments?post=2937"}],"version-history":[{"count":2,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/posts\/2937\/revisions"}],"predecessor-version":[{"id":326257,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/posts\/2937\/revisions\/326257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/media\/2940"}],"wp:attachment":[{"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/media?parent=2937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/categories?post=2937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sideaita.it\/de\/wp-json\/wp\/v2\/tags?post=2937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}