{"id":2937,"date":"2018-09-19T14:57:01","date_gmt":"2018-09-19T12:57:01","guid":{"rendered":"https:\/\/www.sideaita.it\/?p=2937"},"modified":"2024-06-11T12:28:42","modified_gmt":"2024-06-11T10:28:42","slug":"movimiento-motus-upside-down","status":"publish","type":"post","link":"https:\/\/www.sideaita.it\/es\/2018\/09\/19\/motus-upside-down-movement\/","title":{"rendered":"MOTUS: un punto de vista invertido sobre el Movimiento"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p align=\"justify\">\"<em>La naturaleza del hombre est\u00e1 en movimiento: el reposo absoluto es la muerte<\/em>\"(B. Pascal). Que el\u00a0<strong>movimiento<\/strong>\u00a0en la esencia misma del ser humano ya estaba claro en el siglo XVII:\u00a0<strong>es a trav\u00e9s de ella que se puede producir energ\u00eda<\/strong>pero tambi\u00e9n que<strong>armon\u00eda psicof\u00edsica\u00a0<\/strong>que permite expresar plenamente el propio potencial. En sus diversas formas, el movimiento crea las condiciones para una\u00a0<strong>estilo de vida sano y activo,<\/strong>\u00a0que contrasta con el sedentarismo progresivo que abarca una parte cada vez mayor de nuestra vida cotidiana. Estamos sentados cuando trabajamos o estudiamos, estamos sentados cuando comemos, estamos sentados cuando nos desplazamos de un lugar a otro y a menudo estamos sentados incluso cuando hacemos ejercicio.<\/p>\n\n  \n    <div id=\"gallery-1691604012\" class=\"lightbox-multi-gallery slider slider-auto-height row-collapse slider-nav-reveal\" data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 7000}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"579\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695.jpg\" class=\"attachment-original size-original\" alt=\"Motus taller de parada de manos e1536675924695\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-700x540.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-518x400.jpg 518w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-600x463.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-3-e1536675924695-510x394.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-510x765.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-16-600x900.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"618\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819.jpg\" class=\"attachment-original size-original\" alt=\"Motus taller de parada de manos e1536675956819\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-700x577.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-485x400.jpg 485w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-600x494.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-11-e1536675956819-510x420.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237.jpg\" class=\"attachment-original size-original\" alt=\"Motus taller de parada de manos e1536675894237\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-300x300.jpg 300w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-100x100.jpg 100w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-700x700.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-280x280.jpg 280w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-400x400.jpg 400w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-510x510.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-10-e1536675894237-600x600.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-600x900.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-15-510x765.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-600x900.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-14-510x765.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-13-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-533x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1125\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-700x1050.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-267x400.jpg 267w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-533x800.jpg 533w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-510x765.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-12-600x900.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-9-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-700x394.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-711x400.jpg 711w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-510x287.jpg 510w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-7-600x338.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-700x394.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-711x400.jpg 711w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-600x338.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-1-510x287.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-450x800.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"610\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2906,2905,2904,2917,2912,2911,2916,2915,2914,2913,2910,2909,2908,2902,2907\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-700x569.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-492x400.jpg 492w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-600x488.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-6-e1536676038808-510x415.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n<p align=\"justify\">Una respuesta a esta tendencia llega de la mano de un proyecto nacido en Roma que ha hecho de la\u00a0<strong>volver al movimiento<\/strong>\u00a0su enfoque, uniendo diferentes estilos, enfoques y habilidades en torno a este objetivo:\u00a0<strong>Motus<\/strong>\u00a0(\"movimiento\" en lat\u00edn) es <a href=\"https:\/\/www.instagram.com\/lifemotus\/\">una pr\u00e1ctica que tiende al dominio del propio cuerpo como expresi\u00f3n de libertad y bienestar psicof\u00edsico<\/a>.<\/p>\n<p align=\"justify\">Compuesto por figuras de muy diversa procedencia, el Team Motus combina enfoques multidisciplinares orientados a un \u00fanico objetivo, a saber, la exploraci\u00f3n consciente de la dimensi\u00f3n humana y de su potencial a trav\u00e9s del movimiento. Una especie de peque\u00f1a revoluci\u00f3n en el estilo de vida de las personas, a las que no se exige una formaci\u00f3n profesional, ya que se trata de un enfoque gradual y progresivo, sino la simple curiosidad de querer vivir la vida de forma activa y din\u00e1mica, participando en ella y no someti\u00e9ndose a ella.<\/p>\n\n  \n    <div id=\"gallery-1312181604\" class=\"lightbox-multi-gallery slider slider-auto-height row-collapse slider-nav-reveal\" data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 7000}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-27-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-21-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-28-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-20-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-26-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-23-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-24-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-22-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-18-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-19-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"459\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17.jpg\" class=\"attachment-original size-original\" alt=\"motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-700x428.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-654x400.jpg 654w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-600x367.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-17-510x312.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-25-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-31-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30.jpg\" class=\"attachment-original size-original\" alt=\"motus manillar-taller\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-30-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-29-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"width:81%;padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32.jpg\" class=\"attachment-original size-original\" alt=\"Taller de parada de manos Motus\" ids=\"2928,2922,2929,2921,2927,2924,2925,2923,2919,2920,2918,2926,2932,2931,2930,2933\" style=\"normal\" type=\"slider-full\" slider_nav_color=\"light\" auto_slide=\"7000\" image_height=\"56.25%\" image_width=\"81\" image_size=\"original\" srcset=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32.jpg 750w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32-700x467.jpg 700w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32-600x400.jpg 600w, https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-handstand-workshop-32-510x340.jpg 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n<p align=\"justify\"><strong>Fuerza, flexibilidad, movilidad articular, coordinaci\u00f3n, destreza, concentraci\u00f3n y coraje.<\/strong>Estos son s\u00f3lo algunos de los aspectos en los que el planteamiento de\u00a0<strong>Motus<\/strong>uno de los principales protagonistas de la reciente<strong> <a href=\"https:\/\/www.sideaita.it\/es\/2018\/09\/10\/fin-de-semana-de-puertas-abiertas-de-sidea-2018\/\">Fin de semana de puertas abiertas en Sidea<\/a>.\u00a0<\/strong><\/p>\n<p align=\"justify\">Los tres formadores del\u00a0<strong>Equipo Motus,\u00a0<a href=\"https:\/\/www.instagram.com\/kaddarina.motus\/\">Katharina Loestzsch<\/a>,\u00a0<a href=\"https:\/\/www.instagram.com\/lelepagliuca\/\">Emanuele Pagliuca<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/riccardocollins\/\">Richard Collins<\/a>,<\/strong>\u00a0organiz\u00f3 talleres titulados \"<strong>Motus Handstand y transiciones: un punto de vista al rev\u00e9s<\/strong>\" sobre la puesta en pie libre y, m\u00e1s en general, sobre los movimientos din\u00e1micos en el suelo para conseguir mejoras inmediatas en la\u00a0<strong>estabilidad y sentido del equilibrio<\/strong>. \"Un punto de vista al rev\u00e9s\", que por lo tanto no s\u00f3lo se refiere a encontrarse f\u00edsicamente al rev\u00e9s, sino que tambi\u00e9n resume metaf\u00f3ricamente el intento de este grupo de invertir su enfoque de la vida cotidiana. Recordarse a uno mismo que \"<strong>la naturaleza del hombre est\u00e1 en el movimiento<\/strong>\".<\/p>\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/xfSxu9ybqrs?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\n  <div class=\"banner has-hover\" id=\"banner-2069724635\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"319\" src=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2024\/02\/COPERTINA-MAILING-DISCHI-DA-PL-2--1400x438.jpg\" class=\"bg attachment-large size-large\" alt=\"CUBIERTA DISCOS DE CORREO DE PL 2\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-874384118\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2344387805\" class=\"text\">\n\t\t\n<p><strong>BOLET\u00cdN SIDEA<\/strong><\/p>\n<p>Suscr\u00edbase a nuestro bolet\u00edn para recibir noticias, promociones e informaci\u00f3n sobre el mundo de Sidea.<br \/>\n\t\t\n<style>\n#text-2344387805 {\n  font-size: 1.45rem;\n  line-height: 1.25;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"http:\/\/eepurl.com\/iD9wQo\" class=\"button white is-outline is-large\" style=\"border-radius:26px;\">\n\t\t<span>\u00daNASE A<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-874384118 {\n  width: 60%;\n}\n#text-box-874384118 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2069724635 {\n  padding-top: 300px;\n  background-color: rgb(0, 0, 0);\n}\n#banner-2069724635 .overlay {\n  background-color: rgba(0, 0, 0, 0.669);\n}\n<\/style>\n  <\/div>","protected":false},"excerpt":{"rendered":"<p>Motus combina enfoques multidisciplinares orientados a un \u00fanico objetivo: la exploraci\u00f3n de la dimensi\u00f3n humana y su potencial a trav\u00e9s del movimiento.<\/p>","protected":false},"author":3,"featured_media":2940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11447],"tags":[294,278,276],"class_list":["post-2937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-calisthenics","tag-functional-training","tag-sidea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MOTUS: an upside-down point of view on Movement - Sidea Fitness<\/title>\n<meta name=\"description\" content=\"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sideaita.it\/es\/2018\/09\/19\/movimiento-motus-upside-down\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MOTUS: an upside-down point of view on Movement\" \/>\n<meta property=\"og:description\" content=\"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sideaita.it\/es\/2018\/09\/19\/movimiento-motus-upside-down\/\" \/>\n<meta property=\"og:site_name\" content=\"Sidea | Attrezzatura Fitness Professionale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sideaita\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-19T12:57:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T10:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sidea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sidea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\"},\"author\":{\"name\":\"Sidea\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/person\\\/dffac77f9ef1c6ee0bee663f15d9de31\"},\"headline\":\"MOTUS: an upside-down point of view on Movement\",\"datePublished\":\"2018-09-19T12:57:01+00:00\",\"dateModified\":\"2024-06-11T10:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\"},\"wordCount\":500,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"keywords\":[\"calisthenics\",\"functional training\",\"sidea\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\",\"name\":\"MOTUS: an upside-down point of view on Movement - Sidea Fitness\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"datePublished\":\"2018-09-19T12:57:01+00:00\",\"dateModified\":\"2024-06-11T10:28:42+00:00\",\"description\":\"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/motus-workshop-sidea.jpg\",\"width\":1080,\"height\":607,\"caption\":\"motus-workshop-sidea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/2018\\\/09\\\/19\\\/motus-upside-down-movement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sideaita.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MOTUS: an upside-down point of view on Movement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/\",\"name\":\"Sidea | Attrezzatura Fitness Professionale\",\"description\":\"SIDEA \u2013 Allenati, diventa pi\u00f9 forte, vivi meglio | Attrezzatura professionale per la preparazione fisica ed il functional training. Nata dalla passione per lo sport, sviluppata per le palestre.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sideaita.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\",\"name\":\"Sidea Srl\",\"alternateName\":\"Sidea\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-solo-s-1440x1440-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-solo-s-1440x1440-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sidea Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sideaita\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sidea_fitness\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sideafitness\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/sideafitness\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FitnessIT\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sidea_fitness\"],\"description\":\"SIDEA \u2013 Allenati, diventa pi\u00f9 forte, vivi meglio | Attrezzatura professionale per la preparazione fisica ed il functional training. Nata dalla passione per lo sport, sviluppata per le palestre.\",\"email\":\"sidea@sideaita.it\",\"legalName\":\"Sidea Srl\",\"vatID\":\"IT02693190403\",\"taxID\":\"IT02693190403\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.sideaita.it\\\/es\\\/termini-condizioni-di-vendita\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/person\\\/dffac77f9ef1c6ee0bee663f15d9de31\",\"name\":\"Sidea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g\",\"caption\":\"Sidea\"},\"sameAs\":[\"riccardo\"],\"url\":\"https:\\\/\\\/www.sideaita.it\\\/es\\\/author\\\/gioele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MOTUS: un punto de vista invertido sobre el Movimiento - Sidea Fitness","description":"Motus combina enfoques multidisciplinares con un \u00fanico objetivo: explorar la dimensi\u00f3n humana y su potencial a trav\u00e9s del movimiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sideaita.it\/es\/2018\/09\/19\/movimiento-motus-upside-down\/","og_locale":"es_ES","og_type":"article","og_title":"MOTUS: an upside-down point of view on Movement","og_description":"Motus unisce approcci multidisciplinari volti ad un unico obiettivo: un\u2019esplorazione della dimensione umana e delle sue potenzialit\u00e0 attraverso il movimento","og_url":"https:\/\/www.sideaita.it\/es\/2018\/09\/19\/movimiento-motus-upside-down\/","og_site_name":"Sidea | Attrezzatura Fitness Professionale","article_publisher":"https:\/\/www.facebook.com\/sideaita\/","article_published_time":"2018-09-19T12:57:01+00:00","article_modified_time":"2024-06-11T10:28:42+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","type":"image\/jpeg"}],"author":"Sidea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sidea","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#article","isPartOf":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/"},"author":{"name":"Sidea","@id":"https:\/\/www.sideaita.it\/#\/schema\/person\/dffac77f9ef1c6ee0bee663f15d9de31"},"headline":"MOTUS: an upside-down point of view on Movement","datePublished":"2018-09-19T12:57:01+00:00","dateModified":"2024-06-11T10:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/"},"wordCount":500,"commentCount":0,"publisher":{"@id":"https:\/\/www.sideaita.it\/#organization"},"image":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","keywords":["calisthenics","functional training","sidea"],"articleSection":["Eventi"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/","url":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/","name":"MOTUS: un punto de vista invertido sobre el Movimiento - Sidea Fitness","isPartOf":{"@id":"https:\/\/www.sideaita.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage"},"image":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","datePublished":"2018-09-19T12:57:01+00:00","dateModified":"2024-06-11T10:28:42+00:00","description":"Motus combina enfoques multidisciplinares con un \u00fanico objetivo: explorar la dimensi\u00f3n humana y su potencial a trav\u00e9s del movimiento.","breadcrumb":{"@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#primaryimage","url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","contentUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/09\/motus-workshop-sidea.jpg","width":1080,"height":607,"caption":"motus-workshop-sidea"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sideaita.it\/2018\/09\/19\/motus-upside-down-movement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sideaita.it\/"},{"@type":"ListItem","position":2,"name":"MOTUS: an upside-down point of view on Movement"}]},{"@type":"WebSite","@id":"https:\/\/www.sideaita.it\/#website","url":"https:\/\/www.sideaita.it\/","name":"Sidea | Equipos de fitness profesionales","description":"SIDEA - Entrenar, fortalecerse, vivir mejor | Equipamiento profesional para la preparaci\u00f3n f\u00edsica y el entrenamiento funcional. Nacido de la pasi\u00f3n por el deporte, desarrollado para gimnasios.","publisher":{"@id":"https:\/\/www.sideaita.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sideaita.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sideaita.it\/#organization","name":"Sidea Srl","alternateName":"Sidea","url":"https:\/\/www.sideaita.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sideaita.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2023\/06\/cropped-logo-solo-s-1440x1440-1.jpg","contentUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2023\/06\/cropped-logo-solo-s-1440x1440-1.jpg","width":512,"height":512,"caption":"Sidea Srl"},"image":{"@id":"https:\/\/www.sideaita.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sideaita\/","https:\/\/www.instagram.com\/sidea_fitness\/","https:\/\/www.linkedin.com\/company\/sideafitness\/","https:\/\/www.pinterest.it\/sideafitness\/","https:\/\/www.youtube.com\/user\/FitnessIT\/","https:\/\/www.tiktok.com\/@sidea_fitness"],"description":"SIDEA - Entrenar, fortalecerse, vivir mejor | Equipamiento profesional para la preparaci\u00f3n f\u00edsica y el entrenamiento funcional. Nacido de la pasi\u00f3n por el deporte, desarrollado para gimnasios.","email":"sidea@sideaita.it","legalName":"Sidea Srl","vatID":"IT02693190403","taxID":"IT02693190403","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.sideaita.it\/es\/termini-condizioni-di-vendita\/"}},{"@type":"Person","@id":"https:\/\/www.sideaita.it\/#\/schema\/person\/dffac77f9ef1c6ee0bee663f15d9de31","name":"Sidea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f053fd372d4715dae69f2348830136846525c9c803cd9d3899b193518df4fe1?s=96&d=mm&r=g","caption":"Sidea"},"sameAs":["riccardo"],"url":"https:\/\/www.sideaita.it\/es\/author\/gioele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/posts\/2937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/comments?post=2937"}],"version-history":[{"count":2,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/posts\/2937\/revisions"}],"predecessor-version":[{"id":326257,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/posts\/2937\/revisions\/326257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/media\/2940"}],"wp:attachment":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/media?parent=2937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/categories?post=2937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/tags?post=2937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}