{"id":823,"date":"2018-07-29T22:54:15","date_gmt":"2018-07-29T20:54:15","guid":{"rendered":"https:\/\/www.sideaita.it\/?post_type=product&#038;p=823"},"modified":"2026-09-02T12:25:46","modified_gmt":"2026-09-02T10:25:46","slug":"0513-0518-elasticos-power-loop","status":"publish","type":"product","link":"https:\/\/www.sideaita.it\/es\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/","title":{"rendered":"0513-0518 El\u00e1sticos Power Loop"},"content":{"rendered":"<h2>BUCLE DE ALIMENTACI\u00d3N<\/h2>\n<p>Los Power Loops son bandas el\u00e1sticas de alta resistencia, de 1000 mm de longitud, que pueden utilizarse para muchas aplicaciones: dominadas en barra, entrenamiento con barra, carrera por parejas, ejercicios de cuerpo libre contra resistencia.<\/p>\n<p>La resistencia de las bandas el\u00e1sticas es progresiva. Para permitir una orientaci\u00f3n pr\u00e1ctica y eficaz entre las diferentes bandas el\u00e1sticas, damos dos indicaciones de resistencia expresadas en kilogramos: la primera se refiere a la fuerza necesaria para que la banda el\u00e1stica empiece a deformarse, es decir, a estirarse, mientras que la segunda se refiere a la fuerza necesaria para estirar la banda el\u00e1stica +100 cm.<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<h4><strong>Modelo Power Loop<\/strong><\/h4>\n<\/td>\n<td>\n<h4><strong>Color<\/strong><\/h4>\n<\/td>\n<td>\n<h4><strong>Fuerza necesaria para que comience a deformarse<\/strong><\/h4>\n<\/td>\n<td>\n<h4><strong>Fuerza necesaria para extenderlo +100 cm\u00a0<\/strong><\/h4>\n<\/td>\n<\/tr>\n<tr>\n<td><strong><span class=\"notranslate\">c\u00f3digo 0513<\/span> el\u00e1stico SLIM<\/strong><\/td>\n<td><span style=\"font-weight: 400;\">Rojo<\/span><\/td>\n<td><span style=\"font-weight: 400;\">5 Kg<\/span><\/td>\n<td><span style=\"font-weight: 400;\">6 Kg<\/span><\/td>\n<\/tr>\n<tr>\n<td><strong><span class=\"notranslate\">c\u00f3digo 0514<\/span> MINI el\u00e1stico<\/strong><\/td>\n<td><span style=\"font-weight: 400;\">Negro<\/span><\/td>\n<td><span style=\"font-weight: 400;\">10 Kg<\/span><\/td>\n<td><span style=\"font-weight: 400;\">12 Kg<\/span><\/td>\n<\/tr>\n<tr>\n<td><strong><span class=\"notranslate\">c\u00f3digo 0515<\/span> el\u00e1stico X-LIGHT<\/strong><\/td>\n<td><span style=\"font-weight: 400;\">Viola<\/span><\/td>\n<td><span style=\"font-weight: 400;\">15 Kg<\/span><\/td>\n<td><span style=\"font-weight: 400;\">20 Kg<\/span><\/td>\n<\/tr>\n<tr>\n<td><strong><span class=\"notranslate\">c\u00f3digo 0516<\/span> LUZ el\u00e1stica<\/strong><\/td>\n<td><span style=\"font-weight: 400;\">Verde<\/span><\/td>\n<td><span style=\"font-weight: 400;\">20 Kg<\/span><\/td>\n<td><span style=\"font-weight: 400;\">30 Kg<\/span><\/td>\n<\/tr>\n<tr>\n<td><strong><span class=\"notranslate\">c\u00f3digo 0517<\/span> MEDIO el\u00e1stico<\/strong><\/td>\n<td><span style=\"font-weight: 400;\">Azul<\/span><\/td>\n<td><span style=\"font-weight: 400;\">25 Kg<\/span><\/td>\n<td><span style=\"font-weight: 400;\">50 Kg<\/span><\/td>\n<\/tr>\n<tr>\n<td><strong><span class=\"notranslate\">c\u00f3digo 0518<\/span> el\u00e1stico FUERTE<\/strong><\/td>\n<td><span style=\"font-weight: 400;\">Naranja<\/span><\/td>\n<td><span style=\"font-weight: 400;\">30 Kg<\/span><\/td>\n<td><span style=\"font-weight: 400;\">60 Kg<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Se trata de valores aproximados, que hemos querido expresar en kilogramos para permitir una orientaci\u00f3n pr\u00e1ctica. Por tanto, el bucle de potencia <span class=\"notranslate\">c\u00f3digo 0518<\/span>de color naranja, muy resistente, comienza a estirarse con una fuerza de 30 kg, llegando a 60 kg cuando su alargamiento alcanza un metro.<\/p>\n<p>Las resistencias comprendidas entre 0513 y 0516 son las m\u00e1s utilizadas en Muscle Up asistido.<\/p>\n<h3><strong>Insight: el bucle de poder<\/strong><\/h3>\n<p>I <strong>Bucle de potencia<\/strong> son bandas el\u00e1sticas de bucle cerrado, disponibles en varios tama\u00f1os y resistencias, y han alcanzado un gran \u00e9xito en los \u00faltimos a\u00f1os debido al creciente inter\u00e9s por la<strong>entrenamiento funcional<\/strong>. La resistencia con bandas el\u00e1sticas ya es conocida y utilizada desde hace a\u00f1os por muchos entrenadores de atletismo y\/o expertos en calistenia. Los entrenadores de atletismo que ya no son muy j\u00f3venes recordar\u00e1n perfectamente el uso de las c\u00e1maras de aire de las ruedas de bicicleta utilizadas para fortalecer los m\u00fasculos, realizar ejercicios de tracci\u00f3n o como \"vig\u00edas\" para ejercicios m\u00e1s dif\u00edciles.<\/p>\n<p>Uno de los grandes pioneros del entrenamiento auxot\u00f3nico es el fisioterapeuta de la selecci\u00f3n alemana de f\u00fatbol <strong>Erich Deuser<\/strong>. Ya a principios de los a\u00f1os 50, mand\u00f3 fabricar una banda de anillas para fortalecer y entrenar el sistema musculoesquel\u00e9tico de sus atletas y not\u00f3 grandes ventajas en el tratamiento de las dolencias de sus pacientes mediante ejercicios espec\u00edficos. Tambi\u00e9n escribi\u00f3 un manual, \"Die Deuserband Gymnastik\", que es una especie de vadem\u00e9cum sobre ejercicios que pueden realizarse con resistencia el\u00e1stica. El t\u00e9rmino \"entrenamiento funcional\" ya se encuentra en este libro, por lo que, desde el principio, el bucle de potencia es un producto excelente para utilizar en los propios programas de entrenamiento funcional.<\/p>\n<h4><strong>Ventajas y versatilidad<\/strong><\/h4>\n<p>El power loop es una herramienta c\u00f3moda, ligera y vers\u00e1til, f\u00e1cil de usar y de transportar a donde quieras: al parque, de vacaciones, al trabajo o al patio de recreo. Est\u00e1 disponible en diferentes tama\u00f1os y potencias, desde el m\u00e1s peque\u00f1o, el modelo SLIM <span class=\"notranslate\">c\u00f3digo 0513<\/span> (rojo, 6 kg de resistencia medida a 100 cm de elongaci\u00f3n) hasta el m\u00e1s grande, modelo STRONG <span class=\"notranslate\">c\u00f3digo 0518<\/span> (color naranja, resistencia de 60 kg medida a 100 cm de alargamiento).<\/p>\n<p>Una de sus mayores ventajas es que puede anclarse a cualquier estructura, fija o no: ya sea una barra en la que podamos realizar dominadas, un gancho en el suelo o nuestros propios pies, el power loop nos permite realizar cualquier tipo de ejercicio con total seguridad.<\/p>\n<h4><strong>Power Loop y formaci\u00f3n<\/strong><\/h4>\n<p>El uso de este producto se asocia a menudo a la pr\u00e1ctica deportiva, especialmente en la preparaci\u00f3n atl\u00e9tica, y al entrenamiento funcional. De hecho, muchos entrenadores de atletismo complementan las sesiones espec\u00edficas de fuerza con ejercicios m\u00e1s din\u00e1micos y explosivos con el Power Loop. El tipo de contracci\u00f3n muscular es auxot\u00f3nico y aumenta progresivamente a medida que se estira la banda el\u00e1stica. En los ejercicios de campo se prefiere al uso de pesas porque est\u00e1 \"personalizada\", es decir, responde de forma diferente en funci\u00f3n de la fuerza y la explosividad del usuario. Gracias a esta caracter\u00edstica, el tiempo necesario para cargar y\/o descargar la barra casi desaparece, ya que es r\u00e1pida y f\u00e1cil de usar.<\/p>\n<p>Suele proponerse como \"ayuda\" en la ejecuci\u00f3n de ejercicios como Pull-ups y Muscle-ups, ya que proporciona un empuje, en funci\u00f3n de la resistencia del propio Loop, que permite la ejecuci\u00f3n completa del movimiento requerido. Este es uno de los muchos usos que puede tener, pero ser\u00eda realmente reductivo confiarle s\u00f3lo esta caracter\u00edstica. De hecho, el Power Loop permite la ejecuci\u00f3n de los 7 movimientos fundamentales:<\/p>\n<ul>\n<li><strong>En cuclillas<\/strong>sentadilla frontal - sentadilla por encima de la cabeza - tempo squat - split squat<\/li>\n<li><strong>Estocada<\/strong>estocada adelante\/atr\u00e1s\/lateral<\/li>\n<li><strong>Curva<\/strong>buenos d\u00edas - deadlift - swing<\/li>\n<li><strong>Rotaci\u00f3n<\/strong>: rotaci\u00f3n del tronco - woodchop<\/li>\n<li><strong>Tire de<\/strong>remo alto - remo bajo - remo alterno - pull up - chin up<\/li>\n<li><strong>Empuje<\/strong>press de pecho - press de cabeza - extensi\u00f3n de tr\u00edceps - dip<\/li>\n<li><strong>Locomoci\u00f3n<\/strong>correr - saltar - arrastrar los pies - saltar en cuclillas<\/li>\n<\/ul>\n<p>Estos son algunos ejemplos de ejercicios que se pueden realizar con el Power Loop. Su uso suele proponerse en las fases de calentamiento y enfriamiento, ya que permite que el aparato musculoesquel\u00e9tico y neuromuscular aprenda correctamente el movimiento a realizar sin requerir contracciones bruscas y explosivas, que podr\u00edan ser \"perjudiciales\" si no se est\u00e1 preparado para tales esfuerzos. Otra caracter\u00edstica es la \"activaci\u00f3n de todo el cuerpo\". Para realizar correctamente el ejercicio, el Power Loop requiere la activaci\u00f3n del core, ya que el tipo de contracci\u00f3n muscular, que es auxot\u00f3nica, crea una desestabilizaci\u00f3n continua y sin control voluntario y una buena propiocepci\u00f3n ser\u00eda imposible realizar el movimiento. Su utilizaci\u00f3n, sobre todo cuando se asocia al gesto deportivo espec\u00edfico, permite el desarrollo de diferentes capacidades: agilidad, velocidad, potencia y resistencia. No es casualidad que varios entrenadores de atletismo utilicen el Power Loop como resistencia activa a superar durante los distintos movimientos, at\u00e1ndolo a la cintura del deportista o colocando un extremo en la extremidad a fortalecer. En el caso de un tenista, por ejemplo, puede aplicarse eficazmente a la cintura o a los brazos, sujetando un extremo del Power Loop en la mano para simular una raqueta.<\/p>\n<h4><strong>Fitness y m\u00e1s<\/strong><\/h4>\n<p>El uso del Power Loop no s\u00f3lo se limita al mundo del deporte y el fitness, sino que tambi\u00e9n puede extenderse a actividades hol\u00edsticas y fisioterap\u00e9uticas.<\/p>\n<p>En las actividades hol\u00edsticas, ofrece una resistencia que se modifica y gestiona en funci\u00f3n del usuario. Tambi\u00e9n es excelente para ejercicios de tonificaci\u00f3n general, pero tambi\u00e9n como ayuda para estiramientos y ejercicios posturales. La ventaja es que permite al cuerpo alcanzar ciertas posiciones de forma lenta y gradual y poder mantenerlas sin problemas ni fatiga.<\/p>\n<p>En fisioterapia, el Power Loop crea, como ya se ha mencionado, una desestabilizaci\u00f3n que obliga a nuestro cuerpo a modular los movimientos activando los m\u00fasculos profundos, los m\u00fasculos estabilizadores. Ya se trate de un ejercicio de fortalecimiento del manguito de los rotadores o de una marcha r\u00e1pida realizada con un cintur\u00f3n, la banda el\u00e1stica permitir\u00e1 que el ejercicio se realice activando todos los sistemas propioceptivos de nuestro cuerpo para modular su acci\u00f3n.<\/p>\n<p><strong>Mantenimiento<\/strong><\/p>\n<p>Los Power Loops est\u00e1n hechos de l\u00e1tex. Este material es susceptible, con el tiempo, a la evaporaci\u00f3n de las sustancias qu\u00edmicas que hacen que este tipo de caucho sea el\u00e1stico.<br \/>\nPara prolongar la vida \u00fatil de este producto, puede seguir algunos pasos:<\/p>\n<ul>\n<li>Evite guardar los bucles al aire libre y, sobre todo, al sol o bajo una luz intensa: el aire, las fuentes de luz y los rayos UV son acelerantes del deterioro del l\u00e1tex.<\/li>\n<li>Si es posible, gu\u00e1rdalos en una bolsa bien cerrada despu\u00e9s de realizar los ejercicios.<\/li>\n<li>Evite el uso de bucles ancl\u00e1ndolos en componentes con bordes afilados (por ejemplo, algunos estantes para herramientas).<\/li>\n<li>Lavar s\u00f3lo con agua tibia. No utilice productos de limpieza: desengrasantes, alchoolics, aceites son todos agresivos para este material.<\/li>\n<li>Despu\u00e9s de lavarla y siempre antes de usarla, la goma el\u00e1stica debe espolvorearse con polvos de talco. Los polvos de talco reducen en gran medida el deterioro, y facilitan el uso al impedir que el l\u00e1tex se agarre a las manos o a las herramientas, al tiempo que proporcionan un mejor tacto.<\/li>\n<li>En cuanto reciba el el\u00e1stico y tambi\u00e9n regularmente, cada 2-3 meses despu\u00e9s de lavarlo con agua tibia, puede lubricar el el\u00e1stico con un lubricante de silicona, como 'WD-40 Silicone Lubricant' (\u00a1ATENCI\u00d3N! NO WD-40 Standard, que es agresivo). Este procedimiento puede prolongar la vida de la goma el\u00e1stica y evitar la p\u00e1tina blanca t\u00edpica de este material.<\/li>\n<li>No experimentes con la limpieza o la lubricaci\u00f3n con productos que puedan parecer inofensivos: el aceite de vaselina, por ejemplo, es perjudicial para el l\u00e1tex, al igual que el aceite de oliva. Del mismo modo, la amuchina o los desengrasantes son muy perjudiciales. Siga las instrucciones anteriores.<\/li>\n<\/ul>\n<p><strong>V\u00e9ase tambi\u00e9n:<\/strong><\/p>\n<p><a href=\"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0511-medios-de-bucle-de-latex\/\">bacalao. <strong>0511<\/strong> L\u00e1tex Lazo Resistencia Media<\/a><br \/>\n<a href=\"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0512-latex-bucle-fuerte\/\">bacalao. <strong>0512<\/strong> Lazo de l\u00e1tex de gran resistencia<\/a><br \/>\n<a href=\"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0560-0562-bandas-de-latex\/\">bacalao. <strong>0560-0562<\/strong> Banda de l\u00e1tex<\/a><br \/>\n<a href=\"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0606-banda-de-cadera\/\">bacalao. <strong>0606<\/strong> Banda de cadera<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Power Loops son bandas el\u00e1sticas de alta resistencia, de 1000 mm de longitud, disponibles en 6 resistencias diferentes y que pueden utilizarse para una gran variedad de aplicaciones: dominadas con barra, entrenamiento con barra, carrera en pareja, ejercicios de cuerpo libre contra resistencia.<\/p>\n<div><\/div>","protected":false},"featured_media":828,"template":"","meta":[],"product_brand":[],"product_cat":[3466,79,73,83,86,11409,90],"product_tag":[179],"giftcard-category":[],"class_list":["post-823","product","type-product","status-publish","has-post-thumbnail","product_cat-promozioni-usato-corso","product_cat-elastici-bande-fitness","product_cat-calisthenic-rack-attrezzi-allenamento-callistenico","product_cat-attrezzi-functional-training-palestre-professionisti-fitness","product_cat-group-activity","product_cat-occasioni-offerte","product_cat-products-code-order","product_tag-elastici-fitness","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>0513-0518 Power Loop Elastics - Sidea | Attrezzatura Fitness Professionale<\/title>\n<meta name=\"description\" content=\"0513-0518 Power Loop Elastics - Elastici ad alta resistenza, utilizzabili con bilancieri, per aiuto trazioni o corsa trattenuta in coppia.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0513-0518-elasticos-power-loop\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"0513-0518 Power Loop Elastics\" \/>\n<meta property=\"og:description\" content=\"Power Loop Elastici ad alta resistenza diametro \u2248 100 cm (circonferenza \u2248200 cm) utilizzabili per molteplici applicazioni; allenamento con bilancieri, aiuto trazioni, corsa trattenuta in coppia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0513-0518-elasticos-power-loop\/\" \/>\n<meta property=\"og:site_name\" content=\"Sidea | Attrezzatura Fitness Professionale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sideaita\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T10:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/07\/0516-800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Power Loop Elastici ad alta resistenza diametro \u2248 100 cm (circonferenza \u2248200 cm) utilizzabili per molteplici applicazioni; allenamento con bilancieri, aiuto trazioni, corsa trattenuta in coppia.\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilidad\" \/>\n\t<meta name=\"twitter:data1\" content=\"Disponible\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/\",\"name\":\"0513-0518 Power Loop Elastics - Sidea | Attrezzatura Fitness Professionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0516-800.jpg\",\"datePublished\":\"2018-07-29T20:54:15+00:00\",\"dateModified\":\"2026-09-02T10:25:46+00:00\",\"description\":\"0513-0518 Power Loop Elastics - Elastici ad alta resistenza, utilizzabili con bilancieri, per aiuto trazioni o corsa trattenuta in coppia.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0516-800.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0516-800.jpg\",\"width\":700,\"height\":700,\"caption\":\"0513-0518 Power Loop\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/attrezzatura-fitness\\\/0513-0518-power-loop-elastics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sideaita.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elastics and bands fitness\",\"item\":\"https:\\\/\\\/www.sideaita.it\\\/categorie-attrezzi-fitness\\\/elastici-bande-fitness\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"0513-0518 Power Loop Elastics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/\",\"name\":\"Sidea | Attrezzatura Fitness Professionale\",\"description\":\"SIDEA \u2013 Allenati, diventa pi\u00f9 forte, vivi meglio | Attrezzatura professionale per la preparazione fisica ed il functional training. Nata dalla passione per lo sport, sviluppata per le palestre.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sideaita.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#organization\",\"name\":\"Sidea Srl\",\"alternateName\":\"Sidea\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-solo-s-1440x1440-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sideaita.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-solo-s-1440x1440-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sidea Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sideaita.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sideaita\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sidea_fitness\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sideafitness\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/sideafitness\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FitnessIT\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sidea_fitness\"],\"description\":\"SIDEA \u2013 Allenati, diventa pi\u00f9 forte, vivi meglio | Attrezzatura professionale per la preparazione fisica ed il functional training. Nata dalla passione per lo sport, sviluppata per le palestre.\",\"email\":\"sidea@sideaita.it\",\"legalName\":\"Sidea Srl\",\"vatID\":\"IT02693190403\",\"taxID\":\"IT02693190403\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.sideaita.it\\\/es\\\/termini-condizioni-di-vendita\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"POWERLOOP\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"0513-0518 El\u00e1sticos Power Loop - Sidea | Professional Fitness Equipment","description":"0513-0518 Power Loop Elastics - Bandas el\u00e1sticas de alta resistencia, se pueden utilizar con barras de pesas, para ayuda a la tracci\u00f3n o para correr sujetado por parejas.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0513-0518-elasticos-power-loop\/","og_locale":"es_ES","og_type":"article","og_title":"0513-0518 Power Loop Elastics","og_description":"Power Loop Elastici ad alta resistenza diametro \u2248 100 cm (circonferenza \u2248200 cm) utilizzabili per molteplici applicazioni; allenamento con bilancieri, aiuto trazioni, corsa trattenuta in coppia.","og_url":"https:\/\/www.sideaita.it\/es\/equipos-de-fitness\/0513-0518-elasticos-power-loop\/","og_site_name":"Sidea | Attrezzatura Fitness Professionale","article_publisher":"https:\/\/www.facebook.com\/sideaita\/","article_modified_time":"2026-09-02T10:25:46+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/07\/0516-800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"Power Loop Elastici ad alta resistenza diametro \u2248 100 cm (circonferenza \u2248200 cm) utilizzabili per molteplici applicazioni; allenamento con bilancieri, aiuto trazioni, corsa trattenuta in coppia.","twitter_misc":{"Disponibilidad":"Disponible"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/","url":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/","name":"0513-0518 El\u00e1sticos Power Loop - Sidea | Professional Fitness Equipment","isPartOf":{"@id":"https:\/\/www.sideaita.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/#primaryimage"},"image":{"@id":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/07\/0516-800.jpg","datePublished":"2018-07-29T20:54:15+00:00","dateModified":"2026-09-02T10:25:46+00:00","description":"0513-0518 Power Loop Elastics - Bandas el\u00e1sticas de alta resistencia, se pueden utilizar con barras de pesas, para ayuda a la tracci\u00f3n o para correr sujetado por parejas.\u00a0","breadcrumb":{"@id":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/#primaryimage","url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/07\/0516-800.jpg","contentUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2018\/07\/0516-800.jpg","width":700,"height":700,"caption":"0513-0518 Power Loop"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sideaita.it\/attrezzatura-fitness\/0513-0518-power-loop-elastics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sideaita.it\/"},{"@type":"ListItem","position":2,"name":"Prodotti"},{"@type":"ListItem","position":3,"name":"Elastics and bands fitness","item":"https:\/\/www.sideaita.it\/categorie-attrezzi-fitness\/elastici-bande-fitness\/"},{"@type":"ListItem","position":4,"name":"0513-0518 Power Loop Elastics"}]},{"@type":"WebSite","@id":"https:\/\/www.sideaita.it\/#website","url":"https:\/\/www.sideaita.it\/","name":"Sidea | Equipos de fitness profesionales","description":"SIDEA - Entrenar, fortalecerse, vivir mejor | Equipamiento profesional para la preparaci\u00f3n f\u00edsica y el entrenamiento funcional. Nacido de la pasi\u00f3n por el deporte, desarrollado para gimnasios.","publisher":{"@id":"https:\/\/www.sideaita.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sideaita.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sideaita.it\/#organization","name":"Sidea Srl","alternateName":"Sidea","url":"https:\/\/www.sideaita.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sideaita.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2023\/06\/cropped-logo-solo-s-1440x1440-1.jpg","contentUrl":"https:\/\/www.sideaita.it\/wp-content\/uploads\/2023\/06\/cropped-logo-solo-s-1440x1440-1.jpg","width":512,"height":512,"caption":"Sidea Srl"},"image":{"@id":"https:\/\/www.sideaita.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sideaita\/","https:\/\/www.instagram.com\/sidea_fitness\/","https:\/\/www.linkedin.com\/company\/sideafitness\/","https:\/\/www.pinterest.it\/sideafitness\/","https:\/\/www.youtube.com\/user\/FitnessIT\/","https:\/\/www.tiktok.com\/@sidea_fitness"],"description":"SIDEA - Entrenar, fortalecerse, vivir mejor | Equipamiento profesional para la preparaci\u00f3n f\u00edsica y el entrenamiento funcional. Nacido de la pasi\u00f3n por el deporte, desarrollado para gimnasios.","email":"sidea@sideaita.it","legalName":"Sidea Srl","vatID":"IT02693190403","taxID":"IT02693190403","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.sideaita.it\/es\/termini-condizioni-di-vendita\/"}}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"POWERLOOP","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/product\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/media\/828"}],"wp:attachment":[{"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/product_brand?post=823"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/product_cat?post=823"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/product_tag?post=823"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.sideaita.it\/es\/wp-json\/wp\/v2\/giftcard-category?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}